{"id":1122,"date":"2021-02-11T14:03:16","date_gmt":"2021-02-11T14:03:16","guid":{"rendered":"http:\/\/www.morarmais.com.br\/blog\/?p=1122"},"modified":"2021-02-11T21:07:10","modified_gmt":"2021-02-11T21:07:10","slug":"quanto-riso-quanta-alegria","status":"publish","type":"post","link":"https:\/\/morarmais.com.br\/mms\/quanto-riso-quanta-alegria\/","title":{"rendered":"Brasilidade: Quanto riso, oh, quanta alegria!"},"content":{"rendered":"<p style=\"text-align: justify;\">O carnaval brasileiro \u00e9 reconhecido em todo o mundo por sua alegria e inventividade. Por incr\u00edvel que pare\u00e7a, a festa \u00e9 uma heran\u00e7a de comemora\u00e7\u00f5es pag\u00e3s entre os eg\u00edpcios, hebreus, gregos e romanos. J\u00e1 na Idade M\u00e9dia, a Igreja Cat\u00f3lica incorporou as festividades para marcar os \u00faltimos dias de \u201cliberdade\u201d antes da severidade imposta pela Quaresma.<\/p>\n<p style=\"text-align: justify;\">No Brasil col\u00f4nia, os primeiros carnavalescos foram os escravos celebrando uma festa de origem portuguesa: o entrudo. De l\u00e1 para c\u00e1, entre afox\u00e9s, frevos e maracatus e mais tarde as marchinhas e sambas, a coisa pegou!<br \/>Este caldeir\u00e3o de influ\u00eancias liberou geral a criatividade!<br \/>Inspirados por este esp\u00edrito livre, selecionamos alguns ambientes n\u00e3o convencionais e cheios de bossas novas (ou sambas!?!). Seja adepto da folia ou do relax, voc\u00ea com certeza vai adorar o desfile de ideias que selecionamos dos ambientes <a href=\"https:\/\/morarmais.com.br\/mms\/\" target=\"_blank\" rel=\"noopener noreferrer\">Morar Mais<\/a>.<\/p>\n<p><strong>Alegria, alegria!<br \/><\/strong>J\u00e1 na entrada, o Morar Mais Rio de Janeiro esbanjou inventividade. O ambiente causou impacto com paredes feitas de caixas de papel\u00e3o, ora cruas, ora pintadas em padr\u00f5es geom\u00e9tricos coloridos. Achamos o recurso muito bacana para eventos como festas e comemora\u00e7\u00f5es que, quando acaba, pode desmontar e depois reutilizar.<br \/><a href=\"http:\/\/www.morarmais.com.br\/blog\/wp-content\/uploads\/2017\/02\/Morarmais-carnaval-Alegria-_01.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-1124\" src=\"http:\/\/www.morarmais.com.br\/blog\/wp-content\/uploads\/2017\/02\/Morarmais-carnaval-Alegria-_01.jpg\" alt=\"Morarmais-carnaval-Alegria-_01\" width=\"763\" height=\"2455\" srcset=\"https:\/\/morarmais.com.br\/mms\/wp-content\/uploads\/2017\/02\/Morarmais-carnaval-Alegria-_01.jpg 763w, https:\/\/morarmais.com.br\/mms\/wp-content\/uploads\/2017\/02\/Morarmais-carnaval-Alegria-_01-93x300.jpg 93w, https:\/\/morarmais.com.br\/mms\/wp-content\/uploads\/2017\/02\/Morarmais-carnaval-Alegria-_01-318x1024.jpg 318w, https:\/\/morarmais.com.br\/mms\/wp-content\/uploads\/2017\/02\/Morarmais-carnaval-Alegria-_01-500x1609.jpg 500w\" sizes=\"(max-width: 763px) 100vw, 763px\" \/><\/a><\/p>\n<p><em><span style=\"font-size: 8pt;\">GALERIO | <a href=\"https:\/\/www.instagram.com\/cristinenicolay\/\" target=\"_blank\" rel=\"noopener noreferrer\">CRISTINE NICOLA Y LEVINSPUHL<\/a>, COORDINADORA PLATAFORMA DE ARTE URBANA | RIO DE JANEIRO<br \/><\/span><\/em><em><span style=\"font-size: 8pt;\">BILHETERIA-PENSE DENTRO DA CAIXINHA | <a href=\"https:\/\/www.instagram.com\/studiopedrogalaso\/\" target=\"_blank\" rel=\"noopener noreferrer\">PEDRO GALASO<\/a> | RIO DE JANEIRO<\/span><\/em><\/p>\n<p style=\"text-align: justify;\">N\u00e3o d\u00e1 para falar de carnaval sem pensar em cor. Que tal investir em arte para levar um colorido para os ambientes! Quadros e grafites (que nasceram nas ruas e s\u00e3o presen\u00e7a marcante nos interiores descolados) d\u00e3o vida e energia ao decor. M\u00f3veis e almofadas multicoloridos podem fazer parceria com tons neutros e elementos naturais, como madeiras e cimentados para dar um ritmo feliz, mas sem \u00f4ba, \u00f4ba.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.morarmais.com.br\/blog\/wp-content\/uploads\/2017\/02\/Morarmais-carnaval-Alegria-_02.jpg\"><img decoding=\"async\" class=\"alignnone size-full wp-image-1125\" src=\"http:\/\/www.morarmais.com.br\/blog\/wp-content\/uploads\/2017\/02\/Morarmais-carnaval-Alegria-_02.jpg\" alt=\"Morarmais-carnaval-Alegria-_02\" width=\"763\" height=\"3130\" srcset=\"https:\/\/morarmais.com.br\/mms\/wp-content\/uploads\/2017\/02\/Morarmais-carnaval-Alegria-_02.jpg 763w, https:\/\/morarmais.com.br\/mms\/wp-content\/uploads\/2017\/02\/Morarmais-carnaval-Alegria-_02-73x300.jpg 73w, https:\/\/morarmais.com.br\/mms\/wp-content\/uploads\/2017\/02\/Morarmais-carnaval-Alegria-_02-500x2051.jpg 500w\" sizes=\"(max-width: 763px) 100vw, 763px\" \/><\/a><\/p>\n<p><em><span style=\"font-size: 8pt;\">FACHADA ROND\u00d4NIA | PEDRO FERNANDO DE LIMA GERVAZONI &amp; <a href=\"https:\/\/www.instagram.com\/samyrotto\/\" target=\"_blank\" rel=\"noopener noreferrer\">SAMYR OTTO<\/a><br \/><\/span><\/em><em><span style=\"font-size: 8pt;\">FACHADA | <a href=\"https:\/\/www.estudiogamboa.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">LUISA ZACCHE, CAMILA PARIS<\/a>, <a href=\"https:\/\/www.instagram.com\/lindgren.arquitetos\/\" target=\"_blank\" rel=\"noopener noreferrer\">MARCELLO LINDGREN<\/a> &amp; <a href=\"https:\/\/www.instagram.com\/yasmimbolzan\/?hl=pt-br\" target=\"_blank\" rel=\"noopener noreferrer\">YASMIM BOLZAN<\/a> | VIT\u00d3RIA<br \/><\/span><\/em><em><span style=\"font-size: 8pt;\">EST\u00daDIO DA DESIGNER CARIOCA | RICARDO ARRUDA | RIO DE JANEIRO<\/span><\/em><br \/><strong>Leve com voc\u00ea, seus sonhos mais loucos&#8230;<br \/><\/strong>No <a href=\"https:\/\/www.instagram.com\/morarmaisbh\/\" target=\"_blank\" rel=\"noopener noreferrer\">Morar Mais de Belo Horizonte<\/a>, a fantasia rolou solta. A arte entrou em cena com interven\u00e7\u00f5es inusitadas. Tent\u00e1culos brotaram de muros de pedra criando um jardim que subverteu a l\u00f3gica e seduziu o imagin\u00e1rio. Sereias povoaram os azulejos de uma piscina vazia convertida em sala de estar. Em Rond\u00f4nia um muro, antes prosaico, ganhou destaque e humor com uma pintura cheia de<em> nonsense<\/em>.\u00a0 Sim, estamos falando de carnaval, mas se a sua fantasia \u00e9 ir para um p\u00e1tio relaxante, circundado por palmeiras e lago com peixes que nadam pregui\u00e7osamente&#8230; por que n\u00e3o? Ah! Este espa\u00e7o luxuriante do <a href=\"https:\/\/www.instagram.com\/explore\/tags\/morarmaisrondonia\/\" target=\"_blank\" rel=\"noopener noreferrer\">Morar Mais de Rond\u00f4nia<\/a> \u00e9 bacana tamb\u00e9m para o <em>detox<\/em> p\u00f3s-festas.<br \/><a href=\"http:\/\/www.morarmais.com.br\/blog\/wp-content\/uploads\/2017\/02\/Morarmais-carnaval-fantasia_01.jpg\"><img decoding=\"async\" class=\"alignnone wp-image-1127 size-full\" src=\"https:\/\/morarmais.com.br\/mms\/wp-content\/uploads\/2017\/02\/Morarmais-carnaval-fantasia_01.jpg\" alt=\"Morarmais-carnaval-fantasia_01_alegria\" width=\"763\" height=\"1851\" srcset=\"https:\/\/morarmais.com.br\/mms\/wp-content\/uploads\/2017\/02\/Morarmais-carnaval-fantasia_01.jpg 763w, https:\/\/morarmais.com.br\/mms\/wp-content\/uploads\/2017\/02\/Morarmais-carnaval-fantasia_01-124x300.jpg 124w, https:\/\/morarmais.com.br\/mms\/wp-content\/uploads\/2017\/02\/Morarmais-carnaval-fantasia_01-422x1024.jpg 422w, https:\/\/morarmais.com.br\/mms\/wp-content\/uploads\/2017\/02\/Morarmais-carnaval-fantasia_01-500x1213.jpg 500w\" sizes=\"(max-width: 763px) 100vw, 763px\" \/><\/a><a href=\"http:\/\/www.morarmais.com.br\/blog\/wp-content\/uploads\/2017\/02\/Morarmais-carnaval-fantasia_02.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1128 size-full\" src=\"https:\/\/morarmais.com.br\/mms\/wp-content\/uploads\/2017\/02\/Morarmais-carnaval-fantasia_02.jpg\" alt=\"Morarmais-carnaval-fantasia_02_alegria\" width=\"763\" height=\"3019\" srcset=\"https:\/\/morarmais.com.br\/mms\/wp-content\/uploads\/2017\/02\/Morarmais-carnaval-fantasia_02.jpg 763w, https:\/\/morarmais.com.br\/mms\/wp-content\/uploads\/2017\/02\/Morarmais-carnaval-fantasia_02-76x300.jpg 76w, https:\/\/morarmais.com.br\/mms\/wp-content\/uploads\/2017\/02\/Morarmais-carnaval-fantasia_02-259x1024.jpg 259w, https:\/\/morarmais.com.br\/mms\/wp-content\/uploads\/2017\/02\/Morarmais-carnaval-fantasia_02-500x1978.jpg 500w\" sizes=\"(max-width: 763px) 100vw, 763px\" \/><\/a><br \/><span style=\"font-size: 8pt;\"><em>RAMPA DO ARTISTA-ARTE COSTURADA A FOTO | ANGELO ANDRADE, ANA BEATRIZ MORENO, IVANA NEVES, DIOGO ANDRADE &amp; MARCOS FILHO | BELO HORIZONTE<br \/><\/em><\/span><span style=\"font-size: 8pt;\"><em>MERGULHO STUDIOFUTON | <a href=\"https:\/\/www.instagram.com\/machineta\/\" target=\"_blank\" rel=\"noopener noreferrer\">RODRIGO C\u00c2MARA<\/a> | BELO HORIZONTE<br \/><\/em><\/span><span style=\"font-size: 8pt;\"><em>FACHADA ROND\u00d4NIA | PEDRO FERNANDO DE LIMA GERVAZONI &amp; <a href=\"https:\/\/www.instagram.com\/samyrotto\/\" target=\"_blank\" rel=\"noopener noreferrer\">SAMYR OTTO<\/a><br \/><\/em><\/span><span style=\"font-size: 8pt;\"><em>JARDIM CENTRAL | BRUNNA DEOLINDA DE FARIAS PINTO, INGRID ONO &amp; ROS\u00c9LI OLIVEIRA SOUZA<\/em><\/span><\/p>\n<p style=\"text-align: justify;\"><strong>\u00c9 um pouquinho de Brasil, i\u00e1 i\u00e1!<br \/><\/strong>Como homenagem a este espet\u00e1culo que acontece em todo territ\u00f3rio nacional, pin\u00e7amos ambientes com sotaque bem brasileiro. Nesta cozinha de Goi\u00e2nia, ficamos encantados com a fruteira de lou\u00e7a com direito a bananas e macacos. Achamos esta mistura do contempor\u00e2neo e do regional a cara do caldeir\u00e3o cultural que \u00e9 o Brasil. Na composi\u00e7\u00e3o deste quarto modernista, destaque para os azulejos (bem Athos Bulc\u00e3o) que entram em harmonia com os lustres de chap\u00e9us de palha e a cadeira Butterfly, que \u00e9 um cl\u00e1ssico do design internacional.<\/p>\n<p style=\"text-align: justify;\">Mais uma vez o mix e a diversidade entram no ritmo. Como diz a can\u00e7\u00e3o: \u201cchiclete eu misturo com banana e o meu samba vai ficar assim&#8230;\u201d Tamb\u00e9m na loja do Rio, a azulejaria descombinada com jeito de interior, faz contraponto \u00e0s poltronas atual\u00edssimas. Neste bar cheio de ginga em Vit\u00f3ria, uma mesa de sinuca domina o ambiente onde desfilam garrafas de pinga, da boa, e cervejinhas. \u00c9 10! Nota 10!<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.morarmais.com.br\/blog\/wp-content\/uploads\/2017\/02\/Morarmais-carnaval-festabrasileira-_01.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1130 size-full\" title=\"alegria\" src=\"https:\/\/morarmais.com.br\/mms\/wp-content\/uploads\/2017\/02\/Morarmais-carnaval-festabrasileira-_01.jpg\" alt=\"Morarmais-carnaval-festabrasileira-_01\" width=\"763\" height=\"1035\" srcset=\"https:\/\/morarmais.com.br\/mms\/wp-content\/uploads\/2017\/02\/Morarmais-carnaval-festabrasileira-_01.jpg 763w, https:\/\/morarmais.com.br\/mms\/wp-content\/uploads\/2017\/02\/Morarmais-carnaval-festabrasileira-_01-221x300.jpg 221w, https:\/\/morarmais.com.br\/mms\/wp-content\/uploads\/2017\/02\/Morarmais-carnaval-festabrasileira-_01-755x1024.jpg 755w, https:\/\/morarmais.com.br\/mms\/wp-content\/uploads\/2017\/02\/Morarmais-carnaval-festabrasileira-_01-500x678.jpg 500w\" sizes=\"(max-width: 763px) 100vw, 763px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.morarmais.com.br\/blog\/wp-content\/uploads\/2017\/02\/Morarmais-carnaval-festabrasileira-_02.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1131 size-full\" title=\"alegria\" src=\"https:\/\/morarmais.com.br\/mms\/wp-content\/uploads\/2017\/02\/Morarmais-carnaval-festabrasileira-_02.jpg\" alt=\"Morarmais-carnaval-festabrasileira-_02\" width=\"763\" height=\"2150\" srcset=\"https:\/\/morarmais.com.br\/mms\/wp-content\/uploads\/2017\/02\/Morarmais-carnaval-festabrasileira-_02.jpg 763w, https:\/\/morarmais.com.br\/mms\/wp-content\/uploads\/2017\/02\/Morarmais-carnaval-festabrasileira-_02-106x300.jpg 106w, https:\/\/morarmais.com.br\/mms\/wp-content\/uploads\/2017\/02\/Morarmais-carnaval-festabrasileira-_02-363x1024.jpg 363w, https:\/\/morarmais.com.br\/mms\/wp-content\/uploads\/2017\/02\/Morarmais-carnaval-festabrasileira-_02-500x1409.jpg 500w\" sizes=\"(max-width: 763px) 100vw, 763px\" \/><\/a><\/p>\n<p><em><span style=\"font-size: 8pt;\">EST\u00daDIO DOS ARQUITETOS | EDUARDO MEDEIROS, GABRIEL BELA CRUZ &amp; GUSTAVO MIGLIOR\u00cd | GOI\u00c2NIA<br \/><\/span><\/em><em><span style=\"font-size: 8pt;\">QUARTO SUSTENT\u00c1VEL|<a href=\"https:\/\/www.instagram.com\/doloresmarafellinter\/\" target=\"_blank\" rel=\"noopener noreferrer\">DOLORES MARAFELLI<\/a>|RIO DE JANEIRO<br \/><\/span><\/em><em><span style=\"font-size: 8pt;\">LOJA DONA XICA | JOS\u00c9 MARTINS JR | J. MARTINS JR | RIO DE JANEIRO<br \/><\/span><\/em><em><span style=\"font-size: 8pt;\">SALA BAR | <a href=\"https:\/\/www.instagram.com\/decormaisdecor\/\" target=\"_blank\" rel=\"noopener noreferrer\">RENZO CERQUEIRA<\/a> | V\u00cdTORIA<\/span><\/em><\/p>\n\n\n<p>Siga-nos no instagram:\u00a0<a href=\"https:\/\/www.instagram.com\/morarmaispormenos\/\" target=\"_blank\" rel=\"noreferrer noopener\">@morarmaispormenos<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O carnaval brasileiro \u00e9 reconhecido em todo o mundo por sua alegria e inventividade. Por incr\u00edvel que pare\u00e7a, a festa \u00e9 uma heran\u00e7a de comemora\u00e7\u00f5es pag\u00e3s entre os eg\u00edpcios, hebreus, gregos e romanos. J\u00e1 na Idade M\u00e9dia, a Igreja Cat\u00f3lica incorporou as festividades para marcar os \u00faltimos dias de \u201cliberdade\u201d antes da severidade imposta pela&hellip;&nbsp;<a href=\"https:\/\/morarmais.com.br\/mms\/quanto-riso-quanta-alegria\/\" rel=\"bookmark\">Continue a ler &raquo;<span class=\"screen-reader-text\">Brasilidade: Quanto riso, oh, quanta alegria!<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":5260,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_eb_attr":"","editor_plus_copied_stylings":"{}","neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"off","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","_themeisle_gutenberg_block_has_review":false,"_vp_format_video_url":"","_vp_image_focal_point":[],"footnotes":""},"categories":[21,23,31],"tags":[261,167,263,129,51,73,179],"class_list":["post-1122","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-editorial","category-home","category-viciados-em-design","tag-alegria","tag-ambientes-decorados","tag-colorido","tag-inovacao","tag-morar-mais","tag-morar-mais-por-menos","tag-sustentabilidade"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Brasilidade: Quanto riso, oh, quanta alegria! - Morar mais<\/title>\n<meta name=\"description\" content=\"O carnaval brasileiro \u00e9 reconhecido em todo o mundo por sua alegria e inventividade. Conhe\u00e7a o desfile de ideias do Morar Mais.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/morarmais.com.br\/mms\/quanto-riso-quanta-alegria\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Brasilidade: Quanto riso, oh, quanta alegria! - Morar mais\" \/>\n<meta property=\"og:description\" content=\"O carnaval brasileiro \u00e9 reconhecido em todo o mundo por sua alegria e inventividade. Conhe\u00e7a o desfile de ideias do Morar Mais.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/morarmais.com.br\/mms\/quanto-riso-quanta-alegria\/\" \/>\n<meta property=\"og:site_name\" content=\"Morar mais\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/morarmais\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-11T14:03:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-11T21:07:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/morarmais.com.br\/mms\/wp-content\/uploads\/2021\/02\/capa-blog-mais-carnaval.png?fit=852%2C563&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"852\" \/>\n\t<meta property=\"og:image:height\" content=\"563\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"premiata\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"premiata\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/morarmais.com.br\/mms\/quanto-riso-quanta-alegria\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/morarmais.com.br\/mms\/quanto-riso-quanta-alegria\/\"},\"author\":{\"name\":\"premiata\",\"@id\":\"https:\/\/morarmais.com.br\/mms\/#\/schema\/person\/2b6eaad3f24c852077a8e21da2395a85\"},\"headline\":\"Brasilidade: Quanto riso, oh, quanta alegria!\",\"datePublished\":\"2021-02-11T14:03:16+00:00\",\"dateModified\":\"2021-02-11T21:07:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/morarmais.com.br\/mms\/quanto-riso-quanta-alegria\/\"},\"wordCount\":734,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/morarmais.com.br\/mms\/#organization\"},\"image\":{\"@id\":\"https:\/\/morarmais.com.br\/mms\/quanto-riso-quanta-alegria\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/morarmais.com.br\/mms\/wp-content\/uploads\/2021\/02\/capa-blog-mais-carnaval.png\",\"keywords\":[\"Alegria\",\"ambientes decorados\",\"Colorido\",\"inova\u00e7\u00e3o\",\"Morar Mais\",\"Morar Mais por menos\",\"sustentabilidade\"],\"articleSection\":[\"Editorial\",\"Home\",\"Viciados em Design\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/morarmais.com.br\/mms\/quanto-riso-quanta-alegria\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/morarmais.com.br\/mms\/quanto-riso-quanta-alegria\/\",\"url\":\"https:\/\/morarmais.com.br\/mms\/quanto-riso-quanta-alegria\/\",\"name\":\"Brasilidade: Quanto riso, oh, quanta alegria! - Morar mais\",\"isPartOf\":{\"@id\":\"https:\/\/morarmais.com.br\/mms\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/morarmais.com.br\/mms\/quanto-riso-quanta-alegria\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/morarmais.com.br\/mms\/quanto-riso-quanta-alegria\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/morarmais.com.br\/mms\/wp-content\/uploads\/2021\/02\/capa-blog-mais-carnaval.png\",\"datePublished\":\"2021-02-11T14:03:16+00:00\",\"dateModified\":\"2021-02-11T21:07:10+00:00\",\"description\":\"O carnaval brasileiro \u00e9 reconhecido em todo o mundo por sua alegria e inventividade. Conhe\u00e7a o desfile de ideias do Morar Mais.\",\"breadcrumb\":{\"@id\":\"https:\/\/morarmais.com.br\/mms\/quanto-riso-quanta-alegria\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/morarmais.com.br\/mms\/quanto-riso-quanta-alegria\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/morarmais.com.br\/mms\/quanto-riso-quanta-alegria\/#primaryimage\",\"url\":\"https:\/\/morarmais.com.br\/mms\/wp-content\/uploads\/2021\/02\/capa-blog-mais-carnaval.png\",\"contentUrl\":\"https:\/\/morarmais.com.br\/mms\/wp-content\/uploads\/2021\/02\/capa-blog-mais-carnaval.png\",\"width\":852,\"height\":563},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/morarmais.com.br\/mms\/quanto-riso-quanta-alegria\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/morarmais.com.br\/mms\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Brasilidade: Quanto riso, oh, quanta alegria!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/morarmais.com.br\/mms\/#website\",\"url\":\"https:\/\/morarmais.com.br\/mms\/\",\"name\":\"Morar mais\",\"description\":\"O Chique que cabe no bolso\",\"publisher\":{\"@id\":\"https:\/\/morarmais.com.br\/mms\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/morarmais.com.br\/mms\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/morarmais.com.br\/mms\/#organization\",\"name\":\"Morar mais\",\"url\":\"https:\/\/morarmais.com.br\/mms\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/morarmais.com.br\/mms\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/morarmais.com.br\/mms\/wp-content\/uploads\/2019\/04\/cropped-logo-morar-mais-2-1-e1688661143585.png\",\"contentUrl\":\"https:\/\/morarmais.com.br\/mms\/wp-content\/uploads\/2019\/04\/cropped-logo-morar-mais-2-1-e1688661143585.png\",\"width\":130,\"height\":100,\"caption\":\"Morar mais\"},\"image\":{\"@id\":\"https:\/\/morarmais.com.br\/mms\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/morarmais\",\"https:\/\/www.instagram.com\/morarmaispormenos\",\"https:\/\/br.pinterest.com\/morarmais\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/morarmais.com.br\/mms\/#\/schema\/person\/2b6eaad3f24c852077a8e21da2395a85\",\"name\":\"premiata\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/morarmais.com.br\/mms\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g\",\"caption\":\"premiata\"},\"url\":\"https:\/\/morarmais.com.br\/mms\/author\/premiata\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Brasilidade: Quanto riso, oh, quanta alegria! - Morar mais","description":"O carnaval brasileiro \u00e9 reconhecido em todo o mundo por sua alegria e inventividade. Conhe\u00e7a o desfile de ideias do Morar Mais.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/morarmais.com.br\/mms\/quanto-riso-quanta-alegria\/","og_locale":"pt_BR","og_type":"article","og_title":"Brasilidade: Quanto riso, oh, quanta alegria! - Morar mais","og_description":"O carnaval brasileiro \u00e9 reconhecido em todo o mundo por sua alegria e inventividade. Conhe\u00e7a o desfile de ideias do Morar Mais.","og_url":"https:\/\/morarmais.com.br\/mms\/quanto-riso-quanta-alegria\/","og_site_name":"Morar mais","article_publisher":"https:\/\/www.facebook.com\/morarmais","article_published_time":"2021-02-11T14:03:16+00:00","article_modified_time":"2021-02-11T21:07:10+00:00","og_image":[{"width":852,"height":563,"url":"https:\/\/i0.wp.com\/morarmais.com.br\/mms\/wp-content\/uploads\/2021\/02\/capa-blog-mais-carnaval.png?fit=852%2C563&ssl=1","type":"image\/png"}],"author":"premiata","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"premiata","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/morarmais.com.br\/mms\/quanto-riso-quanta-alegria\/#article","isPartOf":{"@id":"https:\/\/morarmais.com.br\/mms\/quanto-riso-quanta-alegria\/"},"author":{"name":"premiata","@id":"https:\/\/morarmais.com.br\/mms\/#\/schema\/person\/2b6eaad3f24c852077a8e21da2395a85"},"headline":"Brasilidade: Quanto riso, oh, quanta alegria!","datePublished":"2021-02-11T14:03:16+00:00","dateModified":"2021-02-11T21:07:10+00:00","mainEntityOfPage":{"@id":"https:\/\/morarmais.com.br\/mms\/quanto-riso-quanta-alegria\/"},"wordCount":734,"commentCount":0,"publisher":{"@id":"https:\/\/morarmais.com.br\/mms\/#organization"},"image":{"@id":"https:\/\/morarmais.com.br\/mms\/quanto-riso-quanta-alegria\/#primaryimage"},"thumbnailUrl":"https:\/\/morarmais.com.br\/mms\/wp-content\/uploads\/2021\/02\/capa-blog-mais-carnaval.png","keywords":["Alegria","ambientes decorados","Colorido","inova\u00e7\u00e3o","Morar Mais","Morar Mais por menos","sustentabilidade"],"articleSection":["Editorial","Home","Viciados em Design"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/morarmais.com.br\/mms\/quanto-riso-quanta-alegria\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/morarmais.com.br\/mms\/quanto-riso-quanta-alegria\/","url":"https:\/\/morarmais.com.br\/mms\/quanto-riso-quanta-alegria\/","name":"Brasilidade: Quanto riso, oh, quanta alegria! - Morar mais","isPartOf":{"@id":"https:\/\/morarmais.com.br\/mms\/#website"},"primaryImageOfPage":{"@id":"https:\/\/morarmais.com.br\/mms\/quanto-riso-quanta-alegria\/#primaryimage"},"image":{"@id":"https:\/\/morarmais.com.br\/mms\/quanto-riso-quanta-alegria\/#primaryimage"},"thumbnailUrl":"https:\/\/morarmais.com.br\/mms\/wp-content\/uploads\/2021\/02\/capa-blog-mais-carnaval.png","datePublished":"2021-02-11T14:03:16+00:00","dateModified":"2021-02-11T21:07:10+00:00","description":"O carnaval brasileiro \u00e9 reconhecido em todo o mundo por sua alegria e inventividade. Conhe\u00e7a o desfile de ideias do Morar Mais.","breadcrumb":{"@id":"https:\/\/morarmais.com.br\/mms\/quanto-riso-quanta-alegria\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/morarmais.com.br\/mms\/quanto-riso-quanta-alegria\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/morarmais.com.br\/mms\/quanto-riso-quanta-alegria\/#primaryimage","url":"https:\/\/morarmais.com.br\/mms\/wp-content\/uploads\/2021\/02\/capa-blog-mais-carnaval.png","contentUrl":"https:\/\/morarmais.com.br\/mms\/wp-content\/uploads\/2021\/02\/capa-blog-mais-carnaval.png","width":852,"height":563},{"@type":"BreadcrumbList","@id":"https:\/\/morarmais.com.br\/mms\/quanto-riso-quanta-alegria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/morarmais.com.br\/mms\/"},{"@type":"ListItem","position":2,"name":"Brasilidade: Quanto riso, oh, quanta alegria!"}]},{"@type":"WebSite","@id":"https:\/\/morarmais.com.br\/mms\/#website","url":"https:\/\/morarmais.com.br\/mms\/","name":"Morar mais","description":"O Chique que cabe no bolso","publisher":{"@id":"https:\/\/morarmais.com.br\/mms\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/morarmais.com.br\/mms\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/morarmais.com.br\/mms\/#organization","name":"Morar mais","url":"https:\/\/morarmais.com.br\/mms\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/morarmais.com.br\/mms\/#\/schema\/logo\/image\/","url":"https:\/\/morarmais.com.br\/mms\/wp-content\/uploads\/2019\/04\/cropped-logo-morar-mais-2-1-e1688661143585.png","contentUrl":"https:\/\/morarmais.com.br\/mms\/wp-content\/uploads\/2019\/04\/cropped-logo-morar-mais-2-1-e1688661143585.png","width":130,"height":100,"caption":"Morar mais"},"image":{"@id":"https:\/\/morarmais.com.br\/mms\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/morarmais","https:\/\/www.instagram.com\/morarmaispormenos","https:\/\/br.pinterest.com\/morarmais\/"]},{"@type":"Person","@id":"https:\/\/morarmais.com.br\/mms\/#\/schema\/person\/2b6eaad3f24c852077a8e21da2395a85","name":"premiata","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/morarmais.com.br\/mms\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","caption":"premiata"},"url":"https:\/\/morarmais.com.br\/mms\/author\/premiata\/"}]}},"_links":{"self":[{"href":"https:\/\/morarmais.com.br\/mms\/wp-json\/wp\/v2\/posts\/1122"}],"collection":[{"href":"https:\/\/morarmais.com.br\/mms\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/morarmais.com.br\/mms\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/morarmais.com.br\/mms\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/morarmais.com.br\/mms\/wp-json\/wp\/v2\/comments?post=1122"}],"version-history":[{"count":0,"href":"https:\/\/morarmais.com.br\/mms\/wp-json\/wp\/v2\/posts\/1122\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/morarmais.com.br\/mms\/wp-json\/wp\/v2\/media\/5260"}],"wp:attachment":[{"href":"https:\/\/morarmais.com.br\/mms\/wp-json\/wp\/v2\/media?parent=1122"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/morarmais.com.br\/mms\/wp-json\/wp\/v2\/categories?post=1122"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/morarmais.com.br\/mms\/wp-json\/wp\/v2\/tags?post=1122"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}